{"id":2292,"date":"2025-08-09T15:07:26","date_gmt":"2025-08-09T15:07:26","guid":{"rendered":"https:\/\/quantongfastener.com\/?post_type=product&#038;p=2292"},"modified":"2025-08-31T03:40:46","modified_gmt":"2025-08-31T03:40:46","slug":"stainless-steel-din-6923-flange-nut","status":"publish","type":"product","link":"https:\/\/quantongfastener.com\/es\/producto\/stainless-steel-din-6923-flange-nut\/","title":{"rendered":"Tuerca de brida de acero inoxidable DIN 6923"},"content":{"rendered":"<div class=\"fl-row fl-row-full-width fl-row-bg-none fl-node-5e5ccfec8a5fb\" data-node=\"5e5ccfec8a5fb\">\n<div class=\"fl-row-content-wrap\">\n<div class=\"fl-row-content fl-row-full-width fl-node-content\">\n<div class=\"fl-col-group fl-node-5e5ccfec8a644\" data-node=\"5e5ccfec8a644\">\n<div class=\"fl-col fl-node-5e5ccfec8a688\" data-node=\"5e5ccfec8a688\">\n<div class=\"fl-col-content fl-node-content\">\n<div class=\"fl-module fl-module-rich-text fl-node-5e5ccfec8a6d0\" data-node=\"5e5ccfec8a6d0\" data-animation-delay=\"0.0\">\n<div class=\"fl-module-content fl-node-content\">\n<div class=\"fl-rich-text\">\n<div class=\"table_wrap\">\n<table border=\"1\" cellspacing=\"0\">\n<tbody>\n<tr>\n<td valign=\"top\" width=\"161\">Nombre del producto<\/td>\n<td valign=\"top\" width=\"406\">A2-70 Tuerca de brida<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"161\">Talla<\/td>\n<td valign=\"top\" width=\"406\">M5-20<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"161\">Grado<\/td>\n<td valign=\"top\" width=\"406\">SS304\/SS316<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"161\">Material<\/td>\n<td valign=\"top\" width=\"406\">Acero al carbono<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"161\">Tratamiento de superficies<\/td>\n<td valign=\"top\" width=\"406\">Llano<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"161\">Est\u00e1ndar<\/td>\n<td valign=\"top\" width=\"406\">DIN\/ISO<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"161\">Certificado<\/td>\n<td valign=\"top\" width=\"406\">ISO 9001<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"161\">Muestra<\/td>\n<td valign=\"top\" width=\"406\">Muestras gratuitas<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"fl-row fl-row-full-width fl-row-bg-none fl-node-5e5ccfec8ae09\" data-node=\"5e5ccfec8ae09\">\n<div class=\"fl-row-content-wrap\">\n<div class=\"fl-row-content fl-row-full-width fl-node-content\">\n<div class=\"fl-col-group fl-node-5e5ccfec8ae4d\" data-node=\"5e5ccfec8ae4d\">\n<div class=\"fl-col fl-node-5e5ccfec8ae91\" data-node=\"5e5ccfec8ae91\">\n<div class=\"fl-col-content fl-node-content\">\n<div class=\"fl-module fl-module-rich-text fl-node-5e5ccfec8aed9\" data-node=\"5e5ccfec8aed9\" data-animation-delay=\"0.0\">\n<div class=\"fl-module-content fl-node-content\">\n<div class=\"fl-rich-text\">\n<p><strong>Uso:<\/strong><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"fl-row fl-row-full-width fl-row-bg-none fl-node-5e5ccfec8bde4\" data-node=\"5e5ccfec8bde4\">\n<div class=\"fl-row-content-wrap\">\n<div class=\"fl-row-content fl-row-full-width fl-node-content\">\n<div class=\"fl-col-group fl-node-5e5ccfec8be26\" data-node=\"5e5ccfec8be26\">\n<div class=\"fl-col fl-node-5e5ccfec8be67 fl-col-has-cols\" data-node=\"5e5ccfec8be67\">\n<div class=\"fl-col-content fl-node-content\">\n<div class=\"fl-module fl-module-rich-text fl-node-5e5ccfec8bea9\" data-node=\"5e5ccfec8bea9\" data-animation-delay=\"0.0\">\n<div class=\"fl-module-content fl-node-content\">\n<div class=\"fl-rich-text\">\n<p>La tuerca con brida se utiliza principalmente para aumentar la superficie de contacto con la pieza de trabajo. Se utiliza sobre todo en tuber\u00edas, y los elementos de fijaci\u00f3n se han estampado y troquelado.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"fl-col-group fl-node-5e5ccfec8bef2 fl-col-group-nested\" data-node=\"5e5ccfec8bef2\">\n<div class=\"fl-col fl-node-5e5ccfec8bf36 fl-col-small\" data-node=\"5e5ccfec8bf36\">\n<div class=\"fl-col-content fl-node-content\">\n<div class=\"fl-module fl-module-rich-text fl-node-5e5ccfec8a777\" data-node=\"5e5ccfec8a777\" data-animation-delay=\"0.0\">\n<div class=\"fl-module-content fl-node-content\">\n<div class=\"fl-rich-text\">\n<p><img decoding=\"async\" class=\"alignnone size-full wp-image-1197\" src=\"https:\/\/www.cyfastener.com\/uploads\/61e39a17.jpg\" alt=\"pc05\" \/><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"fl-col fl-node-5e5ccfec8bf79 fl-col-small\" data-node=\"5e5ccfec8bf79\">\n<div class=\"fl-col-content fl-node-content\">\n<div class=\"fl-module fl-module-rich-text fl-node-5e5ccfec8a728\" data-node=\"5e5ccfec8a728\" data-animation-delay=\"0.0\">\n<div class=\"fl-module-content fl-node-content\">\n<div class=\"fl-rich-text\">\n<p><img decoding=\"async\" class=\"alignnone size-full wp-image-1197\" src=\"https:\/\/www.cyfastener.com\/uploads\/f2453bb6.jpg\" alt=\"pc05\" \/><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"fl-module fl-module-rich-text fl-node-5e5cd097757eb\" data-node=\"5e5cd097757eb\" data-animation-delay=\"0.0\">\n<div class=\"fl-module-content fl-node-content\">\n<div class=\"fl-rich-text\">\n<p>Tuercas de brida y tuercas hexagonales generales son b\u00e1sicamente del mismo tama\u00f1o que las especificaciones de la rosca, pero en comparaci\u00f3n con las tuercas hexagonales, es una junta de una sola pieza y la tuerca, y tiene patrones de dientes antideslizantes debajo, lo que aumenta la tuerca y la pieza de trabajo La superficie de contacto es m\u00e1s fuerte y m\u00e1s fuerte que la combinaci\u00f3n de tuerca ordinaria y la arandela.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"fl-col-group fl-node-5e5cd0b236f94 fl-col-group-nested\" data-node=\"5e5cd0b236f94\">\n<div class=\"fl-col fl-node-5e5cd0b2375da fl-col-small\" data-node=\"5e5cd0b2375da\">\n<div class=\"fl-col-content fl-node-content\">\n<div class=\"fl-module fl-module-rich-text fl-node-5e5cd0bbc7baa\" data-node=\"5e5cd0bbc7baa\" data-animation-delay=\"0.0\">\n<div class=\"fl-module-content fl-node-content\">\n<div class=\"fl-rich-text\">\n<p><img decoding=\"async\" class=\"alignnone size-full wp-image-1197\" src=\"https:\/\/www.cyfastener.com\/uploads\/3db4dc7f.jpg\" alt=\"pc05\" \/><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"fl-col fl-node-5e5cd0b23762a fl-col-small\" data-node=\"5e5cd0b23762a\">\n<div class=\"fl-col-content fl-node-content\">\n<div class=\"fl-module fl-module-rich-text fl-node-5e5cd0c0e428b\" data-node=\"5e5cd0c0e428b\" data-animation-delay=\"0.0\">\n<div class=\"fl-module-content fl-node-content\">\n<div class=\"fl-rich-text\">\n<p><img decoding=\"async\" class=\"alignnone size-full wp-image-1197\" src=\"https:\/\/www.cyfastener.com\/uploads\/159e2c72.jpg\" alt=\"pc05\" \/><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"fl-col fl-node-5e5cd0b237679 fl-col-small\" data-node=\"5e5cd0b237679\">\n<div class=\"fl-col-content fl-node-content\">\n<div class=\"fl-module fl-module-rich-text fl-node-5e5cd0c4e8750\" data-node=\"5e5cd0c4e8750\" data-animation-delay=\"0.0\">\n<div class=\"fl-module-content fl-node-content\">\n<div class=\"fl-rich-text\">\n<p><img decoding=\"async\" class=\"alignnone size-full wp-image-1197\" src=\"https:\/\/www.cyfastener.com\/uploads\/d0cbd87b.jpg\" alt=\"pc05\" \/><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"fl-module fl-module-rich-text fl-node-5e5cd10f8fe97\" data-node=\"5e5cd10f8fe97\" data-animation-delay=\"0.0\">\n<div class=\"fl-module-content fl-node-content\">\n<div class=\"fl-rich-text\">\n<p>Las especificaciones habituales de las tuercas con brida suelen ser inferiores a M20, porque la mayor\u00eda de las tuercas con brida se utilizan en tuber\u00edas y bridas.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"fl-col-group fl-node-5e5cd12677a1b fl-col-group-nested\" data-node=\"5e5cd12677a1b\">\n<div class=\"fl-col fl-node-5e5cd12678012 fl-col-small\" data-node=\"5e5cd12678012\">\n<div class=\"fl-col-content fl-node-content\">\n<div class=\"fl-module fl-module-rich-text fl-node-5e5cd1293edbd\" data-node=\"5e5cd1293edbd\" data-animation-delay=\"0.0\">\n<div class=\"fl-module-content fl-node-content\">\n<div class=\"fl-rich-text\">\n<p><img decoding=\"async\" class=\"alignnone size-full wp-image-1197\" src=\"https:\/\/www.cyfastener.com\/uploads\/5743419c.jpg\" alt=\"pc05\" \/><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"fl-col fl-node-5e5cd1267805f fl-col-small\" data-node=\"5e5cd1267805f\">\n<div class=\"fl-col-content fl-node-content\">\n<div class=\"fl-module fl-module-rich-text fl-node-5e5cd12e5bfd1\" data-node=\"5e5cd12e5bfd1\" data-animation-delay=\"0.0\">\n<div class=\"fl-module-content fl-node-content\">\n<div class=\"fl-rich-text\">\n<p><img decoding=\"async\" class=\"alignnone size-full wp-image-1197\" src=\"https:\/\/www.cyfastener.com\/uploads\/b0dcd80a.jpg\" alt=\"pc05\" \/><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"fl-col-group fl-node-5e7c106e6d167 fl-col-group-nested\" data-node=\"5e7c106e6d167\">\n<div class=\"fl-col fl-node-5e7c106e6d642 fl-col-small\" data-node=\"5e7c106e6d642\">\n<div class=\"fl-col-content fl-node-content\">\n<div class=\"fl-module fl-module-rich-text fl-node-5e5cd132b486d\" data-node=\"5e5cd132b486d\" data-animation-delay=\"0.0\">\n<div class=\"fl-module-content fl-node-content\">\n<div class=\"fl-rich-text\">\n<p><img decoding=\"async\" class=\"alignnone size-full wp-image-1197\" src=\"https:\/\/www.cyfastener.com\/uploads\/97751816.jpg\" alt=\"pc05\" \/><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"fl-col fl-node-5e7c106e6d691 fl-col-small\" data-node=\"5e7c106e6d691\">\n<div class=\"fl-col-content fl-node-content\">\n<div class=\"fl-module fl-module-rich-text fl-node-5e5cd13797da2\" data-node=\"5e5cd13797da2\" data-animation-delay=\"0.0\">\n<div class=\"fl-module-content fl-node-content\">\n<div class=\"fl-rich-text\">\n<p><img decoding=\"async\" class=\"alignnone size-full wp-image-1197\" src=\"https:\/\/www.cyfastener.com\/uploads\/80d6a560.jpg\" alt=\"pc05\" \/><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"fl-row fl-row-full-width fl-row-bg-none fl-node-5e5ccfec8af20\" data-node=\"5e5ccfec8af20\">\n<div class=\"fl-row-content-wrap\">\n<div class=\"fl-row-content fl-row-full-width fl-node-content\">\n<div class=\"fl-col-group fl-node-5e5ccfec8af65\" data-node=\"5e5ccfec8af65\">\n<div class=\"fl-col fl-node-5e5ccfec8afa8\" data-node=\"5e5ccfec8afa8\">\n<div class=\"fl-col-content fl-node-content\">\n<div class=\"fl-module fl-module-rich-text fl-node-5e5ccfec8aff3\" data-node=\"5e5ccfec8aff3\" data-animation-delay=\"0.0\">\n<div class=\"fl-module-content fl-node-content\">\n<div class=\"fl-rich-text\">\n<p><strong>Preguntas frecuentes sobre el acero inoxidable:<\/strong><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"fl-row fl-row-full-width fl-row-bg-none fl-node-5e5ccfec8bd25\" data-node=\"5e5ccfec8bd25\">\n<div class=\"fl-row-content-wrap\">\n<div class=\"fl-row-content fl-row-full-width fl-node-content\">\n<div class=\"fl-col-group fl-node-5e5ccfec8bd60\" data-node=\"5e5ccfec8bd60\">\n<div class=\"fl-col fl-node-5e5ccfec8bda3\" data-node=\"5e5ccfec8bda3\">\n<div class=\"fl-col-content fl-node-content\">\n<div class=\"fl-module fl-module-rich-text fl-node-5e5ccfec8a813\" data-node=\"5e5ccfec8a813\" data-animation-delay=\"0.0\">\n<div class=\"fl-module-content fl-node-content\">\n<div class=\"fl-rich-text\">\n<p>P: \u00bfPor qu\u00e9 es magn\u00e9tico el acero inoxidable?<br \/>\nR: El acero inoxidable 304 pertenece a los aceros inoxidables austen\u00edticos. La austenita se transforma parcial o ligeramente en martensita durante el trabajo en fr\u00edo. La martensita es magn\u00e9tica, por lo que el acero inoxidable es no magn\u00e9tico o d\u00e9bilmente magn\u00e9tico.<br \/>\nP: \u00bfC\u00f3mo identificar los productos de acero inoxidable aut\u00e9nticos?<br \/>\nR: 1. Soporta la prueba de poci\u00f3n especial de acero inoxidable, si no cambia de color, es aut\u00e9ntico acero inoxidable.<br \/>\n2.Apoyar el an\u00e1lisis de la composici\u00f3n qu\u00edmica y el an\u00e1lisis espectral.<br \/>\n3. Apoyar la prueba de humo para simular el entorno de uso real.<br \/>\nP: \u00bfCu\u00e1les son los aceros inoxidables m\u00e1s utilizados?<br \/>\nA: 1.SS201, apto para uso en ambiente seco, f\u00e1cil de oxidar en agua.<br \/>\n2.SS304, ambiente exterior o h\u00famedo, fuerte resistencia a la corrosi\u00f3n y al \u00e1cido.<br \/>\n3.SS316, molibdeno a\u00f1adido, m\u00e1s resistencia a la corrosi\u00f3n, especialmente adecuado para agua de mar y medios qu\u00edmicos.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"fl-row fl-row-full-width fl-row-bg-none fl-node-5e5ccfec8c213\" data-node=\"5e5ccfec8c213\">\n<div class=\"fl-row-content-wrap\">\n<div class=\"fl-row-content fl-row-full-width fl-node-content\">\n<div class=\"fl-col-group fl-node-5e5ccfec8c256\" data-node=\"5e5ccfec8c256\">\n<div class=\"fl-col fl-node-5e5ccfec8c299\" data-node=\"5e5ccfec8c299\">\n<div class=\"fl-col-content fl-node-content\">\n<div class=\"fl-module fl-module-rich-text fl-node-5e5ccfec8c2dc\" data-node=\"5e5ccfec8c2dc\" data-animation-delay=\"0.0\">\n<div class=\"fl-module-content fl-node-content\">\n<div class=\"fl-rich-text\">\n<p><strong>Cinco ventajas del acero inoxidable:<\/strong><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"fl-row fl-row-full-width fl-row-bg-none fl-node-5e5ccfec8c329\" data-node=\"5e5ccfec8c329\">\n<div class=\"fl-row-content-wrap\">\n<div class=\"fl-row-content fl-row-full-width fl-node-content\">\n<div class=\"fl-col-group fl-node-5e5ccfec8c36f\" data-node=\"5e5ccfec8c36f\">\n<div class=\"fl-col fl-node-5e5ccfec8c3b3\" data-node=\"5e5ccfec8c3b3\">\n<div class=\"fl-col-content fl-node-content\">\n<div class=\"fl-module fl-module-rich-text fl-node-5e5ccfec8c3f6\" data-node=\"5e5ccfec8c3f6\" data-animation-delay=\"0.0\">\n<div class=\"fl-module-content fl-node-content\">\n<div class=\"fl-rich-text\">\n<p>1. La dureza del acero inoxidable es m\u00e1s de 2 veces superior a la del cobre, m\u00e1s de 10 veces superior a la del aluminio, el procesamiento es dif\u00edcil, y el proceso de producci\u00f3n es complicado.<br \/>\n2.Durable y no oxidado -- hecho de acero inoxidable, la combinaci\u00f3n de cromo y n\u00edquel crea una capa de anti-oxidaci\u00f3n en la superficie del material, que desempe\u00f1a el papel de la oxidaci\u00f3n.<br \/>\n3.Respetuoso con el medio ambiente, no t\u00f3xico y no contaminante --- El material de acero inoxidable ha sido reconocido como sanitario, seguro, no t\u00f3xico y resistente a \u00e1cidos y \u00e1lcalis. No se libera al mar y no contamina el agua del grifo.<br \/>\n4. Los productos de acero inoxidable son populares en todo el mundo. La superficie es plateada y blanca. Despu\u00e9s de diez a\u00f1os de uso, nunca se oxida. Siempre y cuando se limpie con agua limpia, ser\u00e1 limpio y hermoso, tan brillante como nuevo.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"fl-row fl-row-full-width fl-row-bg-none fl-node-5e5ccfec8b039\" data-node=\"5e5ccfec8b039\">\n<div class=\"fl-row-content-wrap\">\n<div class=\"fl-row-content fl-row-full-width fl-node-content\">\n<div class=\"fl-col-group fl-node-5e5ccfec8b07c\" data-node=\"5e5ccfec8b07c\">\n<div class=\"fl-col fl-node-5e5ccfec8b0bf\" data-node=\"5e5ccfec8b0bf\">\n<div class=\"fl-col-content fl-node-content\">\n<div class=\"fl-module fl-module-rich-text fl-node-5e5ccfec8b102\" data-node=\"5e5ccfec8b102\" data-animation-delay=\"0.0\">\n<div class=\"fl-module-content fl-node-content\">\n<div class=\"fl-rich-text\">\n<p><strong>Par\u00e1metros del producto:<\/strong><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"fl-row fl-row-full-width fl-row-bg-none fl-node-5e5ccfec8bc52\" data-node=\"5e5ccfec8bc52\">\n<div class=\"fl-row-content-wrap\">\n<div class=\"fl-row-content fl-row-full-width fl-node-content\">\n<div class=\"fl-col-group fl-node-5e5ccfec8bc9b\" data-node=\"5e5ccfec8bc9b\">\n<div class=\"fl-col fl-node-5e5ccfec8bce1\" data-node=\"5e5ccfec8bce1\">\n<div class=\"fl-col-content fl-node-content\">\n<div class=\"fl-module fl-module-rich-text fl-node-5e5ccfec8a858\" data-node=\"5e5ccfec8a858\" data-animation-delay=\"0.0\">\n<div class=\"fl-module-content fl-node-content\">\n<div class=\"fl-rich-text\">\n<p>NORMA DIN 6923<\/p>\n<p><a href=\"http:\/\/k1688.quanqiusou.cn\/uploads\/dcd6faa78.png\"><img decoding=\"async\" class=\"alignnone size-full wp-image-1971\" src=\"http:\/\/k1688.quanqiusou.cn\/uploads\/dcd6faa78.png\" alt=\"pd_1\" \/><\/a>\u00a0<a href=\"http:\/\/k1688.quanqiusou.cn\/uploads\/534d51068.png\"><img decoding=\"async\" class=\"alignnone size-medium wp-image-1972\" src=\"http:\/\/k1688.quanqiusou.cn\/uploads\/534d51068.png\" alt=\"pd_2\" \/><\/a><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Pedido M\u00ednimo:1000PCS<\/p>\n<p>EMBALAJE:BOLSA\/CAJA CON PALET<\/p>\n<p>PUERTO:TIANJIN\/QINGDAO\/SHANGHAI\/NINGBO<\/p>\n<p>ENTREGA:5-30DAYS ON QTY<\/p>\n<p>PAGO:T\/T\/LC<\/p>\n<p>Capacidad de suministro:500 TON PER MONTH<\/p>\n<p>&nbsp;<\/p>\n<ul>\n<li><em>Precio FOB:<\/em>US $0.5 - 9,999 \/ Pieza<\/li>\n<li><em>Cantidad m\u00ednima de pedido:<\/em>100 unidades\/piezas<\/li>\n<li><em>Capacidad de suministro:<\/em>10000 Piezas\/Pieza por Mes<\/li>\n<\/ul>","protected":false},"featured_media":2295,"template":"","meta":{"_kad_post_transparent":"default","_kad_post_title":"","_kad_post_layout":"default","_kad_post_sidebar_id":"","_kad_post_content_style":"default","_kad_post_vertical_padding":"default","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false},"product_brand":[],"product_cat":[55,29],"product_tag":[],"class_list":{"0":"post-2292","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-din-6923-flange-nut","7":"product_cat-nut","9":"first","10":"instock","11":"shipping-taxable","12":"product-type-simple","13":"entry","14":"content-bg","15":"loop-entry"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Stainless Steel DIN 6923 Flange Nut - Quantong Fastener<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/quantongfastener.com\/es\/producto\/stainless-steel-din-6923-flange-nut\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Stainless Steel DIN 6923 Flange Nut - Quantong Fastener\" \/>\n<meta property=\"og:description\" content=\"Min.Order Quantity:1000PCS  PACKAGING:BAG\/BOX WITH PALLET  PORT:TIANJIN\/QINGDAO\/SHANGHAI\/NINGBO  DELIVERY:5-30DAYS ON QTY  PAYMENT:T\/T\/LC  Supply Ability:500 TON PER MONTH  &nbsp;   FOB Price:US $0.5 - 9,999 \/ Piece  Min.Order Quantity:100 Piece\/Pieces  Supply Ability:10000 Piece\/Pieces per Month\" \/>\n<meta property=\"og:url\" content=\"https:\/\/quantongfastener.com\/es\/producto\/stainless-steel-din-6923-flange-nut\/\" \/>\n<meta property=\"og:site_name\" content=\"Quantong Fastener\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-31T03:40:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/quantongfastener.com\/wp-content\/uploads\/2025\/08\/Stainless-Steel-DIN-6923-Flange-Nut-3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"610\" \/>\n\t<meta property=\"og:image:height\" content=\"610\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/quantongfastener.com\\\/product\\\/stainless-steel-din-6923-flange-nut\\\/\",\"url\":\"https:\\\/\\\/quantongfastener.com\\\/product\\\/stainless-steel-din-6923-flange-nut\\\/\",\"name\":\"Stainless Steel DIN 6923 Flange Nut - Quantong Fastener\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/quantongfastener.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/quantongfastener.com\\\/product\\\/stainless-steel-din-6923-flange-nut\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/quantongfastener.com\\\/product\\\/stainless-steel-din-6923-flange-nut\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/quantongfastener.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/Stainless-Steel-DIN-6923-Flange-Nut-3.jpg\",\"datePublished\":\"2025-08-09T15:07:26+00:00\",\"dateModified\":\"2025-08-31T03:40:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/quantongfastener.com\\\/product\\\/stainless-steel-din-6923-flange-nut\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/quantongfastener.com\\\/product\\\/stainless-steel-din-6923-flange-nut\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/quantongfastener.com\\\/product\\\/stainless-steel-din-6923-flange-nut\\\/#primaryimage\",\"url\":\"https:\\\/\\\/quantongfastener.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/Stainless-Steel-DIN-6923-Flange-Nut-3.jpg\",\"contentUrl\":\"https:\\\/\\\/quantongfastener.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/Stainless-Steel-DIN-6923-Flange-Nut-3.jpg\",\"width\":610,\"height\":610},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/quantongfastener.com\\\/product\\\/stainless-steel-din-6923-flange-nut\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/quantongfastener.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Products\",\"item\":\"https:\\\/\\\/quantongfastener.com\\\/products\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Stainless Steel DIN 6923 Flange Nut\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/quantongfastener.com\\\/#website\",\"url\":\"https:\\\/\\\/quantongfastener.com\\\/\",\"name\":\"Quantong Fastener\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/quantongfastener.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/quantongfastener.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/quantongfastener.com\\\/#organization\",\"name\":\"Quantong Fastener\",\"url\":\"https:\\\/\\\/quantongfastener.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/quantongfastener.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/quantongfastener.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/logo.jpg\",\"contentUrl\":\"https:\\\/\\\/quantongfastener.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/logo.jpg\",\"width\":425,\"height\":424,\"caption\":\"Quantong Fastener\"},\"image\":{\"@id\":\"https:\\\/\\\/quantongfastener.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Stainless Steel DIN 6923 Flange Nut - Quantong Fastener","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/quantongfastener.com\/es\/producto\/stainless-steel-din-6923-flange-nut\/","og_locale":"es_ES","og_type":"article","og_title":"Stainless Steel DIN 6923 Flange Nut - Quantong Fastener","og_description":"Min.Order Quantity:1000PCS  PACKAGING:BAG\/BOX WITH PALLET  PORT:TIANJIN\/QINGDAO\/SHANGHAI\/NINGBO  DELIVERY:5-30DAYS ON QTY  PAYMENT:T\/T\/LC  Supply Ability:500 TON PER MONTH  &nbsp;   FOB Price:US $0.5 - 9,999 \/ Piece  Min.Order Quantity:100 Piece\/Pieces  Supply Ability:10000 Piece\/Pieces per Month","og_url":"https:\/\/quantongfastener.com\/es\/producto\/stainless-steel-din-6923-flange-nut\/","og_site_name":"Quantong Fastener","article_modified_time":"2025-08-31T03:40:46+00:00","og_image":[{"width":610,"height":610,"url":"https:\/\/quantongfastener.com\/wp-content\/uploads\/2025\/08\/Stainless-Steel-DIN-6923-Flange-Nut-3.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/quantongfastener.com\/product\/stainless-steel-din-6923-flange-nut\/","url":"https:\/\/quantongfastener.com\/product\/stainless-steel-din-6923-flange-nut\/","name":"Stainless Steel DIN 6923 Flange Nut - Quantong Fastener","isPartOf":{"@id":"https:\/\/quantongfastener.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/quantongfastener.com\/product\/stainless-steel-din-6923-flange-nut\/#primaryimage"},"image":{"@id":"https:\/\/quantongfastener.com\/product\/stainless-steel-din-6923-flange-nut\/#primaryimage"},"thumbnailUrl":"https:\/\/quantongfastener.com\/wp-content\/uploads\/2025\/08\/Stainless-Steel-DIN-6923-Flange-Nut-3.jpg","datePublished":"2025-08-09T15:07:26+00:00","dateModified":"2025-08-31T03:40:46+00:00","breadcrumb":{"@id":"https:\/\/quantongfastener.com\/product\/stainless-steel-din-6923-flange-nut\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/quantongfastener.com\/product\/stainless-steel-din-6923-flange-nut\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/quantongfastener.com\/product\/stainless-steel-din-6923-flange-nut\/#primaryimage","url":"https:\/\/quantongfastener.com\/wp-content\/uploads\/2025\/08\/Stainless-Steel-DIN-6923-Flange-Nut-3.jpg","contentUrl":"https:\/\/quantongfastener.com\/wp-content\/uploads\/2025\/08\/Stainless-Steel-DIN-6923-Flange-Nut-3.jpg","width":610,"height":610},{"@type":"BreadcrumbList","@id":"https:\/\/quantongfastener.com\/product\/stainless-steel-din-6923-flange-nut\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/quantongfastener.com\/"},{"@type":"ListItem","position":2,"name":"Products","item":"https:\/\/quantongfastener.com\/products\/"},{"@type":"ListItem","position":3,"name":"Stainless Steel DIN 6923 Flange Nut"}]},{"@type":"WebSite","@id":"https:\/\/quantongfastener.com\/#website","url":"https:\/\/quantongfastener.com\/","name":"Sujetador Quantong","description":"","publisher":{"@id":"https:\/\/quantongfastener.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/quantongfastener.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/quantongfastener.com\/#organization","name":"Sujetador Quantong","url":"https:\/\/quantongfastener.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/quantongfastener.com\/#\/schema\/logo\/image\/","url":"https:\/\/quantongfastener.com\/wp-content\/uploads\/2025\/07\/logo.jpg","contentUrl":"https:\/\/quantongfastener.com\/wp-content\/uploads\/2025\/07\/logo.jpg","width":425,"height":424,"caption":"Quantong Fastener"},"image":{"@id":"https:\/\/quantongfastener.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/quantongfastener.com\/es\/wp-json\/wp\/v2\/product\/2292","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quantongfastener.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/quantongfastener.com\/es\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quantongfastener.com\/es\/wp-json\/wp\/v2\/media\/2295"}],"wp:attachment":[{"href":"https:\/\/quantongfastener.com\/es\/wp-json\/wp\/v2\/media?parent=2292"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/quantongfastener.com\/es\/wp-json\/wp\/v2\/product_brand?post=2292"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/quantongfastener.com\/es\/wp-json\/wp\/v2\/product_cat?post=2292"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/quantongfastener.com\/es\/wp-json\/wp\/v2\/product_tag?post=2292"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}